{"id":654,"date":"2015-05-13T10:19:41","date_gmt":"2015-05-13T09:19:41","guid":{"rendered":"https:\/\/slurink.nl\/?page_id=654"},"modified":"2021-06-15T15:59:14","modified_gmt":"2021-06-15T14:59:14","slug":"longlife-diesel","status":"publish","type":"page","link":"https:\/\/www.slurink.nl\/de\/longlife-diesel\/","title":{"rendered":"Longlife Diesel"},"content":{"rendered":"<h3><a href=\"https:\/\/www.slurink.nl\/longlife-diesel\/lld_green_logo-2\/\" rel=\"attachment wp-att-1616\" data-slb-group=\"59\" data-slb-internal=\"1616\" data-slb-asset=\"1602386809\" data-slb-active=\"1\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1616\" src=\"https:\/\/www.slurink.nl\/wp-content\/uploads\/LLD_Green_Logo-300x84.png\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/www.slurink.nl\/wp-content\/uploads\/LLD_Green_Logo-300x84.png 300w, https:\/\/www.slurink.nl\/wp-content\/uploads\/LLD_Green_Logo-1024x288.png 1024w, https:\/\/www.slurink.nl\/wp-content\/uploads\/LLD_Green_Logo-768x216.png 768w, https:\/\/www.slurink.nl\/wp-content\/uploads\/LLD_Green_Logo.png 1484w\" alt=\"\" width=\"300\" height=\"84\" \/><\/a><\/h3>\n<h3>Alle informatie over Longlife Diesel Green<\/h3>\n<ul>\n<li><strong><a href=\"https:\/\/www.slurink.nl\/wp-content\/uploads\/LLD_Green_Flyer-NL.pdf\">Longlife Diesel Green<\/a><\/strong><\/li>\n<li><a href=\"https:\/\/www.slurink.nl\/wp-content\/uploads\/Longlife-DIESEL-green-Sicherheitsdatenblatt-Lifetime24-vs1.0-NL.pdf\">Zekerheidsinformatieblad NL<\/a> \/\u00a0<a href=\"https:\/\/www.slurink.nl\/wp-content\/uploads\/Longlife-DIESEL-green-Sicherheitsdatenblatt-Lifetime24-vs1.0.pdf\">Sicherheitsdatenblatt DE<\/a><\/li>\n<\/ul>\n<h3>Overzicht van hoeveelheden en dosering<\/h3>\n<ul>\n<li><a href=\"https:\/\/slurink.nl\/wp-content\/uploads\/Mengenangabe_LLD_ltr.pdf\">Longlife Diesel mengtabellen<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alle informatie over Longlife Diesel Green Longlife Diesel Green Zekerheidsinformatieblad&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-654","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Longlife Diesel - Slurink<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.slurink.nl\/de\/longlife-diesel\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Longlife Diesel - Slurink\" \/>\n<meta property=\"og:description\" content=\"Alle informatie over Longlife Diesel Green Longlife Diesel Green Zekerheidsinformatieblad...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.slurink.nl\/de\/longlife-diesel\/\" \/>\n<meta property=\"og:site_name\" content=\"Slurink\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-15T14:59:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.slurink.nl\/wp-content\/uploads\/LLD_Green_Logo-300x84.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.slurink.nl\\\/de\\\/longlife-diesel\\\/\",\"url\":\"https:\\\/\\\/www.slurink.nl\\\/de\\\/longlife-diesel\\\/\",\"name\":\"Longlife Diesel - Slurink\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.slurink.nl\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.slurink.nl\\\/de\\\/longlife-diesel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.slurink.nl\\\/de\\\/longlife-diesel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.slurink.nl\\\/wp-content\\\/uploads\\\/LLD_Green_Logo-300x84.png\",\"datePublished\":\"2015-05-13T09:19:41+00:00\",\"dateModified\":\"2021-06-15T14:59:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.slurink.nl\\\/de\\\/longlife-diesel\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.slurink.nl\\\/de\\\/longlife-diesel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.slurink.nl\\\/de\\\/longlife-diesel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.slurink.nl\\\/wp-content\\\/uploads\\\/LLD_Green_Logo-300x84.png\",\"contentUrl\":\"https:\\\/\\\/www.slurink.nl\\\/wp-content\\\/uploads\\\/LLD_Green_Logo-300x84.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.slurink.nl\\\/de\\\/longlife-diesel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.slurink.nl\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Longlife Diesel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.slurink.nl\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.slurink.nl\\\/de\\\/\",\"name\":\"Slurink\",\"description\":\"Bunkerpunten in Dordrecht, Amsterdam, Lobith, Zaltbommel, Hansweert en Vlissingen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.slurink.nl\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Longlife Diesel - Slurink","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.slurink.nl\/de\/longlife-diesel\/","og_locale":"de_DE","og_type":"article","og_title":"Longlife Diesel - Slurink","og_description":"Alle informatie over Longlife Diesel Green Longlife Diesel Green Zekerheidsinformatieblad...","og_url":"https:\/\/www.slurink.nl\/de\/longlife-diesel\/","og_site_name":"Slurink","article_modified_time":"2021-06-15T14:59:14+00:00","og_image":[{"url":"https:\/\/www.slurink.nl\/wp-content\/uploads\/LLD_Green_Logo-300x84.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.slurink.nl\/de\/longlife-diesel\/","url":"https:\/\/www.slurink.nl\/de\/longlife-diesel\/","name":"Longlife Diesel - Slurink","isPartOf":{"@id":"https:\/\/www.slurink.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.slurink.nl\/de\/longlife-diesel\/#primaryimage"},"image":{"@id":"https:\/\/www.slurink.nl\/de\/longlife-diesel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.slurink.nl\/wp-content\/uploads\/LLD_Green_Logo-300x84.png","datePublished":"2015-05-13T09:19:41+00:00","dateModified":"2021-06-15T14:59:14+00:00","breadcrumb":{"@id":"https:\/\/www.slurink.nl\/de\/longlife-diesel\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.slurink.nl\/de\/longlife-diesel\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.slurink.nl\/de\/longlife-diesel\/#primaryimage","url":"https:\/\/www.slurink.nl\/wp-content\/uploads\/LLD_Green_Logo-300x84.png","contentUrl":"https:\/\/www.slurink.nl\/wp-content\/uploads\/LLD_Green_Logo-300x84.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.slurink.nl\/de\/longlife-diesel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.slurink.nl\/de\/"},{"@type":"ListItem","position":2,"name":"Longlife Diesel"}]},{"@type":"WebSite","@id":"https:\/\/www.slurink.nl\/de\/#website","url":"https:\/\/www.slurink.nl\/de\/","name":"Slurink","description":"Bunkerpunten in Dordrecht, Amsterdam, Lobith, Zaltbommel, Hansweert en Vlissingen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.slurink.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.slurink.nl\/de\/wp-json\/wp\/v2\/pages\/654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.slurink.nl\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.slurink.nl\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.slurink.nl\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.slurink.nl\/de\/wp-json\/wp\/v2\/comments?post=654"}],"version-history":[{"count":6,"href":"https:\/\/www.slurink.nl\/de\/wp-json\/wp\/v2\/pages\/654\/revisions"}],"predecessor-version":[{"id":1637,"href":"https:\/\/www.slurink.nl\/de\/wp-json\/wp\/v2\/pages\/654\/revisions\/1637"}],"wp:attachment":[{"href":"https:\/\/www.slurink.nl\/de\/wp-json\/wp\/v2\/media?parent=654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}